{"id":3914,"date":"2019-11-01T20:50:57","date_gmt":"2019-11-01T18:50:57","guid":{"rendered":"https:\/\/tecnocentres.org\/?p=3914"},"modified":"2020-04-09T14:30:41","modified_gmt":"2020-04-09T12:30:41","slug":"actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula","status":"publish","type":"post","link":"https:\/\/tecnocentres.org\/es\/blog\/2019\/11\/01\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\/","title":{"rendered":"Actualizaci\u00f3n de CLASS-MON: autoevaluaci\u00f3n de la actitud y el trabajo en el aula"},"content":{"rendered":"<p style=\"text-align: justify;\">Hace casi un mes present\u00e9 el complemento para hojas de c\u00e1lculo <a href=\"https:\/\/classmon-es.tecnocentres.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">CLASS-MON<\/a>. Tengo que reconocer que ha tenido mejor acogida de lo que esperaba. Actualmente lo tienen instalado poco m\u00e1s de 11.000 usuarios (fuente <a href=\"https:\/\/gsuite.google.com\/marketplace\/app\/classmon\/56321217732\" target=\"_blank\" rel=\"noopener noreferrer\">G Suite Marketplace<\/a>). Hoy en presento un actualizaci\u00f3n que mejora, b\u00e1sicamente, dos aspectos.<!--more--><\/p>\n<hr \/>\n<h3>Comentarios del profesorado<\/h3>\n<p style=\"text-align: justify;\">Aunque CLASS-MON est\u00e1 m\u00e1s pensado para hacer que los alumnos reflexionen sobre las tareas que realicen que para dar feed-back por parte del profesor, ya que el complemento ofrece la posibilidad de que el profesor eval\u00fae las tareas, he a\u00f1adido la posibilidad de que tambi\u00e9n introduzca comentarios.<\/p>\n<p style=\"text-align: justify;\">Simplemente, en la misma celda donde se introduce la puntuaci\u00f3n de la tarea, se puede utilizar la opci\u00f3n <em>Insertar nota,<\/em> que se muestra con el bot\u00f3n derecho del rat\u00f3n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3915\" src=\"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/11\/1e.png\" alt=\"\" width=\"368\" height=\"587\" srcset=\"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/11\/1e.png 368w, https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/11\/1e-188x300.png 188w\" sizes=\"auto, (max-width: 368px) 100vw, 368px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3918\" src=\"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/11\/2e.png\" alt=\"\" width=\"315\" height=\"234\" srcset=\"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/11\/2e.png 315w, https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/11\/2e-300x223.png 300w\" sizes=\"auto, (max-width: 315px) 100vw, 315px\" \/><\/p>\n<h3>Plantilla actitud<\/h3>\n<p>A algunos alumnos, tambi\u00e9n es interesante ayudarles a aprender a autorregularse el rato de trabajo en el aula. \u00bfAprovechan el tiempo? \u00bfSe concentran y trabajan? \u00bfSe despistan constantemente?<\/p>\n<p>CLASS-MON tambi\u00e9n nos puede servir en estos casos. Cuando se crea la plantilla, ahora CLASS-MON ofrece la posibilidad <em>Actividades<\/em> (que es la plantilla que hasta ahora hab\u00eda) y se ha a\u00f1adido la posibilidad <em>Actitudes.<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3924\" src=\"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/11\/3e.png\" alt=\"\" width=\"646\" height=\"341\" srcset=\"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/11\/3e.png 892w, https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/11\/3e-300x158.png 300w, https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/11\/3e-768x406.png 768w, https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/11\/3e-640x338.png 640w\" sizes=\"auto, (max-width: 646px) 100vw, 646px\" \/><\/p>\n<p>La plantilla, b\u00e1sicamente, se diferencia en las opciones que ofrece en el formulario.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3921\" src=\"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/11\/4e.png\" alt=\"\" width=\"524\" height=\"611\" srcset=\"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/11\/4e.png 524w, https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/11\/4e-257x300.png 257w\" sizes=\"auto, (max-width: 524px) 100vw, 524px\" \/><\/p>\n<p style=\"text-align: justify;\">El alumno se autoeval\u00faa con respecto a la actitud y el trabajo en el aula. En lugar de introducir actividades introduciremos sesiones. Al final de cada sesi\u00f3n, el alumno reflexiona sobre c\u00f3mo ha trabajado y lo indica en el formulario. El profesor tambi\u00e9n puede evaluarlo y as\u00ed el alumno compara si su percepci\u00f3n coincide con la del docente.<\/p>\n<p style=\"text-align: justify;\">Por la experiencia utilizando herramientas similar (hojas de seguimiento, parrillas de trabajo diari &#8230;) en un tanto por ciento importante de los alumnos tiene una repercusi\u00f3n importante, siempre y cuando se limite a un n\u00famero de sesiones concretos. Si se toma como una costumbre, entonces deja de tener efecto.<\/p>\n<hr \/>\n<p style=\"text-align: justify;\">Esta es la primera actualizaci\u00f3n, pero seguro que no ser\u00e1 la \u00faltima. He empezado a recibir <em>feedback<\/em> de profesores que la han empezado a utilizar y esto provoca nuevas ideas y nuevas funcionalidades. Poco a poco intentar\u00e9 ir mejorando la herramienta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace casi un mes present\u00e9 el complemento para hojas de c\u00e1lculo CLASS-MON. Tengo que reconocer que ha tenido mejor acogida de lo que esperaba. Actualmente lo tienen instalado poco m\u00e1s de 11.000 usuarios (fuente G Suite Marketplace). Hoy en presento&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3860,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[98,56,46,61],"tags":[],"class_list":["post-3914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-avaluacio-es","category-google-apps-script-es","category-profesores","category-tic-es","post-archive"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Actualizaci\u00f3n de CLASS-MON: autoevaluaci\u00f3n de la actitud y el trabajo en el aula - Tecnocentres<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tecnocentres.org\/es\/blog\/2019\/11\/01\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Actualizaci\u00f3n de CLASS-MON: autoevaluaci\u00f3n de la actitud y el trabajo en el aula - Tecnocentres\" \/>\n<meta property=\"og:description\" content=\"Hace casi un mes present\u00e9 el complemento para hojas de c\u00e1lculo CLASS-MON. Tengo que reconocer que ha tenido mejor acogida de lo que esperaba. Actualmente lo tienen instalado poco m\u00e1s de 11.000 usuarios (fuente G Suite Marketplace). Hoy en presento...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tecnocentres.org\/es\/blog\/2019\/11\/01\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\/\" \/>\n<meta property=\"og:site_name\" content=\"Tecnocentres\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-01T18:50:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-09T12:30:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/10\/logoclassmon.png\" \/>\n\t<meta property=\"og:image:width\" content=\"371\" \/>\n\t<meta property=\"og:image:height\" content=\"148\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jaume Feliu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jfeliua\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jaume Feliu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/11\\\/01\\\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/11\\\/01\\\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\\\/\"},\"author\":{\"name\":\"Jaume Feliu\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#\\\/schema\\\/person\\\/b2eb569e95072dedf967f0036be08adf\"},\"headline\":\"Actualizaci\u00f3n de CLASS-MON: autoevaluaci\u00f3n de la actitud y el trabajo en el aula\",\"datePublished\":\"2019-11-01T18:50:57+00:00\",\"dateModified\":\"2020-04-09T12:30:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/11\\\/01\\\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\\\/\"},\"wordCount\":389,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/11\\\/01\\\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tecnocentres.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/logoclassmon.png\",\"articleSection\":[\"Avaluaci\u00f3\",\"Google apps script\",\"Profesores\",\"TIC\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/11\\\/01\\\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/11\\\/01\\\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\\\/\",\"url\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/11\\\/01\\\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\\\/\",\"name\":\"Actualizaci\u00f3n de CLASS-MON: autoevaluaci\u00f3n de la actitud y el trabajo en el aula - Tecnocentres\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/11\\\/01\\\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/11\\\/01\\\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tecnocentres.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/logoclassmon.png\",\"datePublished\":\"2019-11-01T18:50:57+00:00\",\"dateModified\":\"2020-04-09T12:30:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#\\\/schema\\\/person\\\/b2eb569e95072dedf967f0036be08adf\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/11\\\/01\\\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/11\\\/01\\\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/11\\\/01\\\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tecnocentres.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/logoclassmon.png\",\"contentUrl\":\"https:\\\/\\\/tecnocentres.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/logoclassmon.png\",\"width\":371,\"height\":148},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/11\\\/01\\\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualizaci\u00f3n de CLASS-MON: autoevaluaci\u00f3n de la actitud y el trabajo en el aula\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/\",\"name\":\"Tecnocentres\",\"description\":\"Blog de Jaume Feliu\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#\\\/schema\\\/person\\\/b2eb569e95072dedf967f0036be08adf\",\"name\":\"Jaume Feliu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g\",\"caption\":\"Jaume Feliu\"},\"sameAs\":[\"https:\\\/\\\/tecnocentres.org\",\"https:\\\/\\\/x.com\\\/jfeliua\"],\"url\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Actualizaci\u00f3n de CLASS-MON: autoevaluaci\u00f3n de la actitud y el trabajo en el aula - Tecnocentres","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tecnocentres.org\/es\/blog\/2019\/11\/01\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\/","og_locale":"es_ES","og_type":"article","og_title":"Actualizaci\u00f3n de CLASS-MON: autoevaluaci\u00f3n de la actitud y el trabajo en el aula - Tecnocentres","og_description":"Hace casi un mes present\u00e9 el complemento para hojas de c\u00e1lculo CLASS-MON. Tengo que reconocer que ha tenido mejor acogida de lo que esperaba. Actualmente lo tienen instalado poco m\u00e1s de 11.000 usuarios (fuente G Suite Marketplace). Hoy en presento...","og_url":"https:\/\/tecnocentres.org\/es\/blog\/2019\/11\/01\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\/","og_site_name":"Tecnocentres","article_published_time":"2019-11-01T18:50:57+00:00","article_modified_time":"2020-04-09T12:30:41+00:00","og_image":[{"width":371,"height":148,"url":"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/10\/logoclassmon.png","type":"image\/png"}],"author":"Jaume Feliu","twitter_card":"summary_large_image","twitter_creator":"@jfeliua","twitter_misc":{"Escrito por":"Jaume Feliu","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/11\/01\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\/#article","isPartOf":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/11\/01\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\/"},"author":{"name":"Jaume Feliu","@id":"https:\/\/tecnocentres.org\/es\/#\/schema\/person\/b2eb569e95072dedf967f0036be08adf"},"headline":"Actualizaci\u00f3n de CLASS-MON: autoevaluaci\u00f3n de la actitud y el trabajo en el aula","datePublished":"2019-11-01T18:50:57+00:00","dateModified":"2020-04-09T12:30:41+00:00","mainEntityOfPage":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/11\/01\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\/"},"wordCount":389,"commentCount":0,"image":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/11\/01\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\/#primaryimage"},"thumbnailUrl":"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/10\/logoclassmon.png","articleSection":["Avaluaci\u00f3","Google apps script","Profesores","TIC"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tecnocentres.org\/es\/blog\/2019\/11\/01\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/11\/01\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\/","url":"https:\/\/tecnocentres.org\/es\/blog\/2019\/11\/01\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\/","name":"Actualizaci\u00f3n de CLASS-MON: autoevaluaci\u00f3n de la actitud y el trabajo en el aula - Tecnocentres","isPartOf":{"@id":"https:\/\/tecnocentres.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/11\/01\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\/#primaryimage"},"image":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/11\/01\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\/#primaryimage"},"thumbnailUrl":"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/10\/logoclassmon.png","datePublished":"2019-11-01T18:50:57+00:00","dateModified":"2020-04-09T12:30:41+00:00","author":{"@id":"https:\/\/tecnocentres.org\/es\/#\/schema\/person\/b2eb569e95072dedf967f0036be08adf"},"breadcrumb":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/11\/01\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tecnocentres.org\/es\/blog\/2019\/11\/01\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/11\/01\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\/#primaryimage","url":"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/10\/logoclassmon.png","contentUrl":"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/10\/logoclassmon.png","width":371,"height":148},{"@type":"BreadcrumbList","@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/11\/01\/actualizacion-de-class-mon-autoevaluacion-de-la-actitud-y-el-trabajo-en-el-aula\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/tecnocentres.org\/es\/"},{"@type":"ListItem","position":2,"name":"Actualizaci\u00f3n de CLASS-MON: autoevaluaci\u00f3n de la actitud y el trabajo en el aula"}]},{"@type":"WebSite","@id":"https:\/\/tecnocentres.org\/es\/#website","url":"https:\/\/tecnocentres.org\/es\/","name":"Tecnocentres","description":"Blog de Jaume Feliu","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tecnocentres.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/tecnocentres.org\/es\/#\/schema\/person\/b2eb569e95072dedf967f0036be08adf","name":"Jaume Feliu","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g","caption":"Jaume Feliu"},"sameAs":["https:\/\/tecnocentres.org","https:\/\/x.com\/jfeliua"],"url":"https:\/\/tecnocentres.org\/es\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/posts\/3914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/comments?post=3914"}],"version-history":[{"count":0,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/posts\/3914\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/media\/3860"}],"wp:attachment":[{"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/media?parent=3914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/categories?post=3914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/tags?post=3914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}