{"id":3637,"date":"2019-02-17T19:14:11","date_gmt":"2019-02-17T17:14:11","guid":{"rendered":"https:\/\/tecnocentres.org\/?p=3637"},"modified":"2019-02-17T19:14:05","modified_gmt":"2019-02-17T17:14:05","slug":"herramientas-para-una-evaluacion-formadora-y-formativa","status":"publish","type":"post","link":"https:\/\/tecnocentres.org\/es\/blog\/2019\/02\/17\/herramientas-para-una-evaluacion-formadora-y-formativa\/","title":{"rendered":"Herramientas para una evaluaci\u00f3n formadora y formativa"},"content":{"rendered":"<h6><a href=\"http:\/\/www.nyphotographic.com\/\">Nick Youngson<\/a>\u00a0<a href=\"http:\/\/creativecommons.org\/licenses\/by-sa\/3.0\/\" rel=\"license\">CC BY-SA 3.0<\/a>\u00a0<a href=\"http:\/\/alphastockimages.com\/\">Alpha Stock Images<\/a><\/h6>\n<p style=\"text-align: justify;\">Muchas veces, cuando hablamos de herramientas para una evaluaci\u00f3n formativa y\/o formadora, ponemos en el mismo saco herramientas inform\u00e1ticas, estrategias y tareas de los alumnos. Como las tres cosas pueden contribuir a esta evaluaci\u00f3n, es normal que suceda. Pero en este art\u00edculo quiero diferenciarlas y ver algunas alternativas para cada aspecto.<\/p>\n<p style=\"text-align: justify;\">Ser\u00e1 un art\u00edculo muy abierto esperando aportaciones de otros profesores que puedan complementar mi conocimiento limitado de herramientas.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Primero definimos muy r\u00e1pidamente evaluaci\u00f3n formativa y formadora. En todo el art\u00edculo me referir\u00e9 a la evaluaci\u00f3n,\u00a0tal y como lo define Neus Sanmart\u00ed a <em>Evaluar para aprender<\/em> (2010), como medio para regular los aprendizajes, es decir, para identificar las dificultades y los errores y encontrar caminos para superarlos.<\/p>\n<p style=\"text-align: justify;\">Citando la misma Neu, la evaluaci\u00f3n <strong>formadora<\/strong> es aquella donde las decisiones las toma fundamentalmente la persona que aprende (el alumno en nuestro caso). La evaluaci\u00f3n <strong>formativa<\/strong> es aquella donde las decisiones las toma fundamentalmente el profesorado.<\/p>\n<p style=\"text-align: justify;\"><strong>Tareas de los alumnos<\/strong><\/p>\n<p style=\"text-align: justify;\">Empezamos por las tareas de los alumnos. Esta es quiz\u00e1 la parte m\u00e1s sencilla. \u00bfQu\u00e9 tareas de los alumnos favorecen m\u00e1s la evaluaci\u00f3n formadora? R\u00e1pidamente pensaremos en portafolios o en diarios de clase. Y, a partir de ah\u00ed, cualquier otra tarea donde el alumno tenga que realizar una reflexi\u00f3n sobre lo que est\u00e1 realizando y sobre lo que est\u00e1 aprendiendo.<\/p>\n<p style=\"text-align: justify;\">Si el alumno debe detenerse para valorar lo que est\u00e1 aprendiendo, seguro que est\u00e1 realizando una evaluaci\u00f3n formativa.<\/p>\n<p style=\"text-align: justify;\">Pero, de hecho, la lista podr\u00eda ser largu\u00edsima. Una redacci\u00f3n, una presentaci\u00f3n oral, un v\u00eddeo sobre alg\u00fan aspecto que se trabaja en el aula, tambi\u00e9n pueden convertirse en tareas que faciliten una evaluaci\u00f3n por parte del propio estudiante y, por tanto, una evaluaci\u00f3n formadora. Y, tambi\u00e9n, por qu\u00e9 no, tareas digitales. Una tarea de EDpuzzle, donde las preguntas inviten a la reflexi\u00f3n del aprendizaje tambi\u00e9n puede ir en el camino de la evaluaci\u00f3n formadora.<\/p>\n<p style=\"text-align: justify;\">Si las tareas las realiza el alumnado, esta realizaci\u00f3n siempre puede provocar una evaluaci\u00f3n formativa, pero no formadora. Es el propio alumno que realiza la actividad y, antes de que la vea el profesor, es \u00e9l quien debe tomar las decisiones para su mejora.<\/p>\n<p style=\"text-align: justify;\"><strong>Estrategias<\/strong><\/p>\n<p style=\"text-align: justify;\">Una vez la tarea, sea la que sea, se ha iniciado, es cuando hay que buscar estrategias que puedan introducir la evaluaci\u00f3n formativa. La estrategia m\u00e1s utilizada es la retroalimentaci\u00f3n (el <em>feed-back<\/em>). Alguien (profesor, compa\u00f1eros, familia, externos&#8230;) revisa la tarea y propone mejoras. Esta retroalimentaci\u00f3n es, sin lugar a dudas, la estrategia m\u00e1s poderosa. \u00bfQu\u00e9 se puede mejorar? Qu\u00e9 est\u00e1 muy bien y hay que seguir realizando igual?<\/p>\n<p style=\"text-align: justify;\">Si en clase tuvi\u00e9ramos 10 alumnos, aqu\u00ed terminar\u00eda la lista de estrategias. Podr\u00edamos dar retroalimentaci\u00f3n constantemente. Mientras el alumno fuese desarrollando (o creando) alguna tarea, tendr\u00eda propuestas de mejora propias, de los profesores y los compa\u00f1eros que le ayudar\u00edan a avanzar. Pero la realidad es la que es y, con 30 alumnos en clase, esta retroalimentaci\u00f3n es mucho menos presente.<\/p>\n<p style=\"text-align: justify;\">Por lo tanto, aparecen otras estrategias que pueden ir bien. El uso de r\u00fabricas, ya sean anal\u00edticas, de un solo punto o hol\u00edsticas, puede favorecer esta evaluaci\u00f3n formativa (y tambi\u00e9n formadora cuando el propio alumno hace la revisi\u00f3n). Ahora bien, utilizar una r\u00fabrica para evaluar de manera formativa no es m\u00e1s que dar una retroalimentaci\u00f3n de manera m\u00e1s ordenada y sistem\u00e1tica. El alumno tiene un referente claro de d\u00f3nde debe llegar y de qu\u00e9 aspectos debe tener en cuenta y, por tanto, es m\u00e1s sencillo que \u00e9l mismo detecte sus carencias (evaluaci\u00f3n formadora) y tambi\u00e9n es m\u00e1s sencillo y r\u00e1pido que el profesor y los compa\u00f1eros le indiquen los aspectos a mejorar. Con esto no quiero quitar importancia a las r\u00fabricas, pero s\u00ed quiero destacar que es la retroalimentaci\u00f3n lo que facilita que el estudiante detecte puntos fuertes y d\u00e9biles y mejore el aprendizaje.<\/p>\n<p style=\"text-align: justify;\">Y aunque no es la intenci\u00f3n del art\u00edculo, aprovecho para romper una lanza en favor de la reducci\u00f3n de ratios. Por s\u00ed sola est\u00e1 comprobado que es una medida con muy poco impacto en los resultados. Pero, reduciendo la ratio de alumnos por profesor, podemos hacer una retroalimentaci\u00f3n mejor en calidad y en cantidad, que s\u00ed es una medida que tiene un alto impacto en los resultados de los alumnos.<\/p>\n<p style=\"text-align: justify;\"><strong>Herramientas inform\u00e1ticas<\/strong><\/p>\n<p style=\"text-align: justify;\">Las herramientas inform\u00e1ticas que nos pueden ayudar en la evaluaci\u00f3n formativa y formadora ser\u00e1n las que nos ayuden en cualquiera de los aspectos anteriores. Encontramos un mont\u00f3n de aplicaciones para el primer aspecto, las tareas de los alumnos. Desde Edpuzzle que ya he citado antes, pasando por Flipgrid, WeVideo, Powntoon o cualquiera de los cientos de aplicaciones que utilizamos con alumnos. Si tenemos claro que los alumnos deben reflexionar sobre las tareas que est\u00e1n realizando y como las est\u00e1n haciendo, pr\u00e1cticamente todas las aplicaciones pueden ser \u00fatiles.<\/p>\n<p style=\"text-align: justify;\">Pero cuando entramos en el segundo aspecto, el de las estrategias, la cosa ya cambia y es m\u00e1s complicado.<\/p>\n<p style=\"text-align: justify;\">Encontramos entornos virtual de aprendizaje (LMS) como Moodle o Classroom que nos permiten retroalimentaci\u00f3n (normalmente a trav\u00e9s de comentarios) con los alumnos. Para m\u00ed, en ambos casos (en uno m\u00e1s que en el otro), esta forma de dar retroalimentaci\u00f3n aun queda lejos de ser r\u00e1pida y \u00e1gil.<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n encontramos documentos colaborativos donde podemos dejar comentarios a los alumnos (l\u00e1stima que no se puedan dejar comentarios en los Sites de Google).<\/p>\n<p style=\"text-align: justify;\">Las aplicaciones de seguimiento de alumnos (como Additio o Idoce) han incorporado las r\u00fabricas, pero como herramienta calificadora. Flipgrid mismo tambi\u00e9n permite evaluar los v\u00eddeos que los alumnos cuelgan con una r\u00fabrica. Pero se utilizan para calificar la tarea. <a href=\"https:\/\/tecnocentres.org\/es\/rubricas-y-evaluacion-formativa\/\" target=\"_blank\" rel=\"noopener\">En alg\u00fan otro art\u00edculo<\/a> ya he dicho que mejor calificar con r\u00fabrica que sin, pero esto solo no es signo de evaluaci\u00f3n formativa (y, menos, formadora).<\/p>\n<p style=\"text-align: justify;\">Barriendo para casa, podr\u00edamos encontrar <a href=\"http:\/\/corubrics-es.tecnocentres.org\/\" target=\"_blank\" rel=\"noopener\">CoRubrics<\/a>, que se puede utilizar como herramienta calificadora y basta. Pero que tambi\u00e9n permite usarla de manera repetida y sin utilizar notas num\u00e9ricas para avanzar m\u00e1s en la l\u00ednea de la evaluaci\u00f3n formativa. Ya puestos, sigo barriendo. Hace poco present\u00e9\u00a0<a href=\"https:\/\/tecnocentres.org\/es\/rubricas-de-un-solo-punto-automatizar-la-comparticion-entre-alumnos\/\" target=\"_blank\" rel=\"noopener\">un peque\u00f1o script para utilizar r\u00fabricas de un solo punto<\/a> de manera \u00e1gil con los alumnos.<\/p>\n<p style=\"text-align: justify;\">Y poco m\u00e1s. Creo que, en este aspecto, a\u00fan tenemos mucho camino por recorrer. Muchos centros han comenzado a desarrollar aplicaciones propias para poder mejorar esta retroacci\u00f3n. Pero son soluciones muy personalizadas, que en muchos casos han tenido que pagar desarrollo a medida y que no son p\u00fablicas.<\/p>\n<p><strong>Conclusi\u00f3n<\/strong><\/p>\n<p style=\"text-align: justify;\">Si queremos avanzar realmente hacia la evaluaci\u00f3n formativa, hay que buscar herramientas en los tres aspectos. Hay que repensar las tareas que los alumnos realizan, hay que mejorar las estrategias que utilizamos para que los alumnos detecten las mejoras a realizar y utilizar (tal vez crear) herramientas inform\u00e1ticas que nos faciliten todo este proceso.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nick Youngson\u00a0CC BY-SA 3.0\u00a0Alpha Stock Images Muchas veces, cuando hablamos de herramientas para una evaluaci\u00f3n formativa y\/o formadora, ponemos en el mismo saco herramientas inform\u00e1ticas, estrategias y tareas de los alumnos. Como las tres cosas pueden contribuir a esta evaluaci\u00f3n,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3640,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42,44],"tags":[],"class_list":["post-3637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion","category-organizacion","post-archive"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Herramientas para una evaluaci\u00f3n formadora y formativa - Tecnocentres<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tecnocentres.org\/es\/blog\/2019\/02\/17\/herramientas-para-una-evaluacion-formadora-y-formativa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Herramientas para una evaluaci\u00f3n formadora y formativa - Tecnocentres\" \/>\n<meta property=\"og:description\" content=\"Nick Youngson\u00a0CC BY-SA 3.0\u00a0Alpha Stock Images Muchas veces, cuando hablamos de herramientas para una evaluaci\u00f3n formativa y\/o formadora, ponemos en el mismo saco herramientas inform\u00e1ticas, estrategias y tareas de los alumnos. Como las tres cosas pueden contribuir a esta evaluaci\u00f3n,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tecnocentres.org\/es\/blog\/2019\/02\/17\/herramientas-para-una-evaluacion-formadora-y-formativa\/\" \/>\n<meta property=\"og:site_name\" content=\"Tecnocentres\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-17T17:14:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/02\/feedback.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jaume Feliu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jfeliua\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jaume Feliu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/02\\\/17\\\/herramientas-para-una-evaluacion-formadora-y-formativa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/02\\\/17\\\/herramientas-para-una-evaluacion-formadora-y-formativa\\\/\"},\"author\":{\"name\":\"Jaume Feliu\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#\\\/schema\\\/person\\\/b2eb569e95072dedf967f0036be08adf\"},\"headline\":\"Herramientas para una evaluaci\u00f3n formadora y formativa\",\"datePublished\":\"2019-02-17T17:14:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/02\\\/17\\\/herramientas-para-una-evaluacion-formadora-y-formativa\\\/\"},\"wordCount\":1229,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/02\\\/17\\\/herramientas-para-una-evaluacion-formadora-y-formativa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tecnocentres.org\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/feedback.jpg\",\"articleSection\":[\"Informaci\u00f3n\",\"Organizaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/02\\\/17\\\/herramientas-para-una-evaluacion-formadora-y-formativa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/02\\\/17\\\/herramientas-para-una-evaluacion-formadora-y-formativa\\\/\",\"url\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/02\\\/17\\\/herramientas-para-una-evaluacion-formadora-y-formativa\\\/\",\"name\":\"Herramientas para una evaluaci\u00f3n formadora y formativa - Tecnocentres\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/02\\\/17\\\/herramientas-para-una-evaluacion-formadora-y-formativa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/02\\\/17\\\/herramientas-para-una-evaluacion-formadora-y-formativa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tecnocentres.org\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/feedback.jpg\",\"datePublished\":\"2019-02-17T17:14:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#\\\/schema\\\/person\\\/b2eb569e95072dedf967f0036be08adf\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/02\\\/17\\\/herramientas-para-una-evaluacion-formadora-y-formativa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/02\\\/17\\\/herramientas-para-una-evaluacion-formadora-y-formativa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/02\\\/17\\\/herramientas-para-una-evaluacion-formadora-y-formativa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tecnocentres.org\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/feedback.jpg\",\"contentUrl\":\"https:\\\/\\\/tecnocentres.org\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/feedback.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Nick Youngson CC BY-SA 3.0 Alpha Stock Images\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/02\\\/17\\\/herramientas-para-una-evaluacion-formadora-y-formativa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Herramientas para una evaluaci\u00f3n formadora y formativa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/\",\"name\":\"Tecnocentres\",\"description\":\"Blog de Jaume Feliu\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#\\\/schema\\\/person\\\/b2eb569e95072dedf967f0036be08adf\",\"name\":\"Jaume Feliu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g\",\"caption\":\"Jaume Feliu\"},\"sameAs\":[\"https:\\\/\\\/tecnocentres.org\",\"https:\\\/\\\/x.com\\\/jfeliua\"],\"url\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Herramientas para una evaluaci\u00f3n formadora y formativa - Tecnocentres","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tecnocentres.org\/es\/blog\/2019\/02\/17\/herramientas-para-una-evaluacion-formadora-y-formativa\/","og_locale":"es_ES","og_type":"article","og_title":"Herramientas para una evaluaci\u00f3n formadora y formativa - Tecnocentres","og_description":"Nick Youngson\u00a0CC BY-SA 3.0\u00a0Alpha Stock Images Muchas veces, cuando hablamos de herramientas para una evaluaci\u00f3n formativa y\/o formadora, ponemos en el mismo saco herramientas inform\u00e1ticas, estrategias y tareas de los alumnos. Como las tres cosas pueden contribuir a esta evaluaci\u00f3n,...","og_url":"https:\/\/tecnocentres.org\/es\/blog\/2019\/02\/17\/herramientas-para-una-evaluacion-formadora-y-formativa\/","og_site_name":"Tecnocentres","article_published_time":"2019-02-17T17:14:11+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/02\/feedback.jpg","type":"image\/jpeg"}],"author":"Jaume Feliu","twitter_card":"summary_large_image","twitter_creator":"@jfeliua","twitter_misc":{"Escrito por":"Jaume Feliu","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/02\/17\/herramientas-para-una-evaluacion-formadora-y-formativa\/#article","isPartOf":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/02\/17\/herramientas-para-una-evaluacion-formadora-y-formativa\/"},"author":{"name":"Jaume Feliu","@id":"https:\/\/tecnocentres.org\/es\/#\/schema\/person\/b2eb569e95072dedf967f0036be08adf"},"headline":"Herramientas para una evaluaci\u00f3n formadora y formativa","datePublished":"2019-02-17T17:14:11+00:00","mainEntityOfPage":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/02\/17\/herramientas-para-una-evaluacion-formadora-y-formativa\/"},"wordCount":1229,"commentCount":0,"image":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/02\/17\/herramientas-para-una-evaluacion-formadora-y-formativa\/#primaryimage"},"thumbnailUrl":"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/02\/feedback.jpg","articleSection":["Informaci\u00f3n","Organizaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tecnocentres.org\/es\/blog\/2019\/02\/17\/herramientas-para-una-evaluacion-formadora-y-formativa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/02\/17\/herramientas-para-una-evaluacion-formadora-y-formativa\/","url":"https:\/\/tecnocentres.org\/es\/blog\/2019\/02\/17\/herramientas-para-una-evaluacion-formadora-y-formativa\/","name":"Herramientas para una evaluaci\u00f3n formadora y formativa - Tecnocentres","isPartOf":{"@id":"https:\/\/tecnocentres.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/02\/17\/herramientas-para-una-evaluacion-formadora-y-formativa\/#primaryimage"},"image":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/02\/17\/herramientas-para-una-evaluacion-formadora-y-formativa\/#primaryimage"},"thumbnailUrl":"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/02\/feedback.jpg","datePublished":"2019-02-17T17:14:11+00:00","author":{"@id":"https:\/\/tecnocentres.org\/es\/#\/schema\/person\/b2eb569e95072dedf967f0036be08adf"},"breadcrumb":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/02\/17\/herramientas-para-una-evaluacion-formadora-y-formativa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tecnocentres.org\/es\/blog\/2019\/02\/17\/herramientas-para-una-evaluacion-formadora-y-formativa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/02\/17\/herramientas-para-una-evaluacion-formadora-y-formativa\/#primaryimage","url":"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/02\/feedback.jpg","contentUrl":"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/02\/feedback.jpg","width":1200,"height":800,"caption":"Nick Youngson CC BY-SA 3.0 Alpha Stock Images"},{"@type":"BreadcrumbList","@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/02\/17\/herramientas-para-una-evaluacion-formadora-y-formativa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/tecnocentres.org\/es\/"},{"@type":"ListItem","position":2,"name":"Herramientas para una evaluaci\u00f3n formadora y formativa"}]},{"@type":"WebSite","@id":"https:\/\/tecnocentres.org\/es\/#website","url":"https:\/\/tecnocentres.org\/es\/","name":"Tecnocentres","description":"Blog de Jaume Feliu","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tecnocentres.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/tecnocentres.org\/es\/#\/schema\/person\/b2eb569e95072dedf967f0036be08adf","name":"Jaume Feliu","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g","caption":"Jaume Feliu"},"sameAs":["https:\/\/tecnocentres.org","https:\/\/x.com\/jfeliua"],"url":"https:\/\/tecnocentres.org\/es\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/posts\/3637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/comments?post=3637"}],"version-history":[{"count":0,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/posts\/3637\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/media\/3640"}],"wp:attachment":[{"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/media?parent=3637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/categories?post=3637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/tags?post=3637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}