{"id":3480,"date":"2019-01-05T14:16:55","date_gmt":"2019-01-05T12:16:55","guid":{"rendered":"https:\/\/tecnocentres.org\/?p=3480"},"modified":"2019-01-05T14:23:02","modified_gmt":"2019-01-05T12:23:02","slug":"permetre-copies-de-formularis-i-de-documents-i-presentacions","status":"publish","type":"post","link":"https:\/\/tecnocentres.org\/es\/blog\/2019\/01\/05\/permetre-copies-de-formularis-i-de-documents-i-presentacions\/","title":{"rendered":"Permitir copias de formularios (y de documentos y presentaciones)"},"content":{"rendered":"\n<p>Google Drive tiene algunos trucos un poco escondidos que es bueno conocer. Algunos de ellos los uso sin saber demasiado quien me los explic\u00f3 o donde los le\u00ed. Y uno de ellos es el de permitir crear copias de un formulario sin que nadie pueda editar el formulario original.<br><\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Pero empecemos por ver c\u00f3mo forzar un copia de un documento. Vamos a crear un enlace que, al hacer clic, ofrezca la posibilidad de crear una copia de un documento.<\/p>\n\n\n\n<p>Basta con abrir el documento y copiar su direcci\u00f3n. Por ejemplo:<\/p>\n\n\n\n<p>https:\/\/docs.google.com\/document\/d\/1plVHr-s9nRYT_IqecvSDAbdJXgz5FVNKTJqx1FSY8ak\/edit<\/p>\n\n\n\n<p>El enlace que fuerza la copia se construye cambiando el final de la direcci\u00f3n. Hay que sustituir el \/edit por un \/copy.<\/p>\n\n\n\n<p>https:\/\/docs.google.com\/document\/d\/1plVHr-s9nRYT_IqecvSDAbdJXgz5FVNKTJqx1FSY8ak\/copy<\/p>\n\n\n\n<p>Eso s\u00ed, para que funcione debemos compartir el documento con permiso de lectura para cualquier persona que tenga el enlace.<\/p>\n\n\n\n<p>Y, justamente eso, es lo que dificulta realizarlo con formularios. Un formulario no tiene permiso de lectura. Cuando se crea un formulario, no hay que compartirlo con lectura. Un formulario siempre est\u00e1 compartido con todas las personas que tengan el enlace, y no se puede evitar (como m\u00e1ximo se puede restringir a los usuarios del dominio si se utiliza en un entorno G Suite for Education).<\/p>\n\n\n\n<p>Un primera prueba ser\u00eda repetir el mismo procedimiento que en los documentos. Sustituir el final por \/copy. Pero solo esto, no funciona, nos aparece la pantalla que indica que no tenemos permisos<\/p>\n\n\n\n<p>\u00bfCu\u00e1l es entonces la soluci\u00f3n? Primero hay que crear una carpeta compartida en modo de lectura para cualquier persona que tenga el enlace.<\/p>\n\n\n\n<p>Luego hay que mover el formulario a esta carpeta (de esta manera es como si le di\u00e9ramos al formulario permiso de lectura adicional).<\/p>\n\n\n\n<p>Finalmente, abrimos el formulario y copiamos su direcci\u00f3n. Ahora s\u00ed, si cambiamos el final de la direcci\u00f3n \/edit por \/copy, todo el mundo que siga el enlace tendr\u00e1 la oportunidad de crearse una copia del formulario y editar la copia. En cambio, no podr\u00e1 tocar el formulario original (como m\u00e1ximo lo podr\u00e1 responder).<\/p>\n\n\n\n<p>El enlace tendr\u00e1 una forma similar a la siguiente:<br><br>https:\/\/docs.google.com\/forms\/d\/1aJ248ncctz7scju_Glmwgm4QsRM2_E5iXy1LrfYVz1w\/edit<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Google Drive t\u00e9 alguns trucs una mica amagats que va b\u00e9 con\u00e8ixer. Alguns d&#8217;ells els utilitzo sense saber massa qui me&#8217;ls va explicar o on ho vaig llegir. I un d&#8217;ells \u00e9s el de permetre fer c\u00f2pies d&#8217;un formulari sense que ning\u00fa pugui editar el nostre formulari original.<\/p>\n","protected":false},"author":1,"featured_media":3478,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50,46],"tags":[],"class_list":["post-3480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gsuite","category-profesores","post-archive"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Permitir copias de formularios (y de documentos y presentaciones) - Tecnocentres<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tecnocentres.org\/es\/blog\/2019\/01\/05\/permetre-copies-de-formularis-i-de-documents-i-presentacions\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Permitir copias de formularios (y de documentos y presentaciones) - Tecnocentres\" \/>\n<meta property=\"og:description\" content=\"Google Drive t\u00e9 alguns trucs una mica amagats que va b\u00e9 con\u00e8ixer. Alguns d&#039;ells els utilitzo sense saber massa qui me&#039;ls va explicar o on ho vaig llegir. I un d&#039;ells \u00e9s el de permetre fer c\u00f2pies d&#039;un formulari sense que ning\u00fa pugui editar el nostre formulari original.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tecnocentres.org\/es\/blog\/2019\/01\/05\/permetre-copies-de-formularis-i-de-documents-i-presentacions\/\" \/>\n<meta property=\"og:site_name\" content=\"Tecnocentres\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-05T12:16:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-05T12:23:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/01\/cf.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"665\" \/>\n\t<meta property=\"og:image:height\" content=\"377\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jaume Feliu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jfeliua\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jaume Feliu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/01\\\/05\\\/permetre-copies-de-formularis-i-de-documents-i-presentacions\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/01\\\/05\\\/permetre-copies-de-formularis-i-de-documents-i-presentacions\\\/\"},\"author\":{\"name\":\"Jaume Feliu\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#\\\/schema\\\/person\\\/b2eb569e95072dedf967f0036be08adf\"},\"headline\":\"Permitir copias de formularios (y de documentos y presentaciones)\",\"datePublished\":\"2019-01-05T12:16:55+00:00\",\"dateModified\":\"2019-01-05T12:23:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/01\\\/05\\\/permetre-copies-de-formularis-i-de-documents-i-presentacions\\\/\"},\"wordCount\":400,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/01\\\/05\\\/permetre-copies-de-formularis-i-de-documents-i-presentacions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tecnocentres.org\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/cf.jpg\",\"articleSection\":[\"gsuite\",\"Profesores\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/01\\\/05\\\/permetre-copies-de-formularis-i-de-documents-i-presentacions\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/01\\\/05\\\/permetre-copies-de-formularis-i-de-documents-i-presentacions\\\/\",\"url\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/01\\\/05\\\/permetre-copies-de-formularis-i-de-documents-i-presentacions\\\/\",\"name\":\"Permitir copias de formularios (y de documentos y presentaciones) - Tecnocentres\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/01\\\/05\\\/permetre-copies-de-formularis-i-de-documents-i-presentacions\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/01\\\/05\\\/permetre-copies-de-formularis-i-de-documents-i-presentacions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tecnocentres.org\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/cf.jpg\",\"datePublished\":\"2019-01-05T12:16:55+00:00\",\"dateModified\":\"2019-01-05T12:23:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#\\\/schema\\\/person\\\/b2eb569e95072dedf967f0036be08adf\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/01\\\/05\\\/permetre-copies-de-formularis-i-de-documents-i-presentacions\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/01\\\/05\\\/permetre-copies-de-formularis-i-de-documents-i-presentacions\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/01\\\/05\\\/permetre-copies-de-formularis-i-de-documents-i-presentacions\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tecnocentres.org\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/cf.jpg\",\"contentUrl\":\"https:\\\/\\\/tecnocentres.org\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/cf.jpg\",\"width\":665,\"height\":377},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2019\\\/01\\\/05\\\/permetre-copies-de-formularis-i-de-documents-i-presentacions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Permitir copias de formularios (y de documentos y presentaciones)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/\",\"name\":\"Tecnocentres\",\"description\":\"Blog de Jaume Feliu\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#\\\/schema\\\/person\\\/b2eb569e95072dedf967f0036be08adf\",\"name\":\"Jaume Feliu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g\",\"caption\":\"Jaume Feliu\"},\"sameAs\":[\"https:\\\/\\\/tecnocentres.org\",\"https:\\\/\\\/x.com\\\/jfeliua\"],\"url\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Permitir copias de formularios (y de documentos y presentaciones) - Tecnocentres","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tecnocentres.org\/es\/blog\/2019\/01\/05\/permetre-copies-de-formularis-i-de-documents-i-presentacions\/","og_locale":"es_ES","og_type":"article","og_title":"Permitir copias de formularios (y de documentos y presentaciones) - Tecnocentres","og_description":"Google Drive t\u00e9 alguns trucs una mica amagats que va b\u00e9 con\u00e8ixer. Alguns d'ells els utilitzo sense saber massa qui me'ls va explicar o on ho vaig llegir. I un d'ells \u00e9s el de permetre fer c\u00f2pies d'un formulari sense que ning\u00fa pugui editar el nostre formulari original.","og_url":"https:\/\/tecnocentres.org\/es\/blog\/2019\/01\/05\/permetre-copies-de-formularis-i-de-documents-i-presentacions\/","og_site_name":"Tecnocentres","article_published_time":"2019-01-05T12:16:55+00:00","article_modified_time":"2019-01-05T12:23:02+00:00","og_image":[{"width":665,"height":377,"url":"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/01\/cf.jpg","type":"image\/jpeg"}],"author":"Jaume Feliu","twitter_card":"summary_large_image","twitter_creator":"@jfeliua","twitter_misc":{"Escrito por":"Jaume Feliu","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/01\/05\/permetre-copies-de-formularis-i-de-documents-i-presentacions\/#article","isPartOf":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/01\/05\/permetre-copies-de-formularis-i-de-documents-i-presentacions\/"},"author":{"name":"Jaume Feliu","@id":"https:\/\/tecnocentres.org\/es\/#\/schema\/person\/b2eb569e95072dedf967f0036be08adf"},"headline":"Permitir copias de formularios (y de documentos y presentaciones)","datePublished":"2019-01-05T12:16:55+00:00","dateModified":"2019-01-05T12:23:02+00:00","mainEntityOfPage":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/01\/05\/permetre-copies-de-formularis-i-de-documents-i-presentacions\/"},"wordCount":400,"commentCount":0,"image":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/01\/05\/permetre-copies-de-formularis-i-de-documents-i-presentacions\/#primaryimage"},"thumbnailUrl":"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/01\/cf.jpg","articleSection":["gsuite","Profesores"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tecnocentres.org\/es\/blog\/2019\/01\/05\/permetre-copies-de-formularis-i-de-documents-i-presentacions\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/01\/05\/permetre-copies-de-formularis-i-de-documents-i-presentacions\/","url":"https:\/\/tecnocentres.org\/es\/blog\/2019\/01\/05\/permetre-copies-de-formularis-i-de-documents-i-presentacions\/","name":"Permitir copias de formularios (y de documentos y presentaciones) - Tecnocentres","isPartOf":{"@id":"https:\/\/tecnocentres.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/01\/05\/permetre-copies-de-formularis-i-de-documents-i-presentacions\/#primaryimage"},"image":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/01\/05\/permetre-copies-de-formularis-i-de-documents-i-presentacions\/#primaryimage"},"thumbnailUrl":"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/01\/cf.jpg","datePublished":"2019-01-05T12:16:55+00:00","dateModified":"2019-01-05T12:23:02+00:00","author":{"@id":"https:\/\/tecnocentres.org\/es\/#\/schema\/person\/b2eb569e95072dedf967f0036be08adf"},"breadcrumb":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/01\/05\/permetre-copies-de-formularis-i-de-documents-i-presentacions\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tecnocentres.org\/es\/blog\/2019\/01\/05\/permetre-copies-de-formularis-i-de-documents-i-presentacions\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/01\/05\/permetre-copies-de-formularis-i-de-documents-i-presentacions\/#primaryimage","url":"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/01\/cf.jpg","contentUrl":"https:\/\/tecnocentres.org\/wp-content\/uploads\/2019\/01\/cf.jpg","width":665,"height":377},{"@type":"BreadcrumbList","@id":"https:\/\/tecnocentres.org\/es\/blog\/2019\/01\/05\/permetre-copies-de-formularis-i-de-documents-i-presentacions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/tecnocentres.org\/es\/"},{"@type":"ListItem","position":2,"name":"Permitir copias de formularios (y de documentos y presentaciones)"}]},{"@type":"WebSite","@id":"https:\/\/tecnocentres.org\/es\/#website","url":"https:\/\/tecnocentres.org\/es\/","name":"Tecnocentres","description":"Blog de Jaume Feliu","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tecnocentres.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/tecnocentres.org\/es\/#\/schema\/person\/b2eb569e95072dedf967f0036be08adf","name":"Jaume Feliu","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g","caption":"Jaume Feliu"},"sameAs":["https:\/\/tecnocentres.org","https:\/\/x.com\/jfeliua"],"url":"https:\/\/tecnocentres.org\/es\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/posts\/3480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/comments?post=3480"}],"version-history":[{"count":0,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/posts\/3480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/media\/3478"}],"wp:attachment":[{"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/media?parent=3480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/categories?post=3480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/tags?post=3480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}