{"id":3410,"date":"2018-10-11T18:30:41","date_gmt":"2018-10-11T16:30:41","guid":{"rendered":"https:\/\/tecnocentres.org\/?p=3410"},"modified":"2018-10-11T18:29:32","modified_gmt":"2018-10-11T16:29:32","slug":"rubricas-y-evaluacion-formativa","status":"publish","type":"post","link":"https:\/\/tecnocentres.org\/es\/blog\/2018\/10\/11\/rubricas-y-evaluacion-formativa\/","title":{"rendered":"R\u00fabricas y evaluaci\u00f3n formativa"},"content":{"rendered":"<p style=\"text-align: justify;\">Mucha gente todav\u00eda cree que evaluar con r\u00fabricas es realizar evaluaci\u00f3n formativa y, en muchos casos, no es as\u00ed. Una r\u00fabrica, de hecho, proporciona criterios claros a la hora de evaluar una tarea. Ahora bien, esto se puede hacer para que el alumno detecte sus errores y sus puntos fuertes y para que reflexione sobre su aprendizaje (evaluaci\u00f3n formativa) o se puede hacer de forma simplemente mec\u00e1nica para calificar tareas (evaluaci\u00f3n sumativa o certificadora).<\/p>\n<p style=\"text-align: justify;\">No reniego de ninguna de las dos, tanto sea para evaluaci\u00f3n formativa como para evaluaci\u00f3n sumativa, utilizar r\u00fabricas <strong>siempre<\/strong> es positivo. El alumno conoce los criterios que se utilizar\u00e1n para evaluar una tarea. Y eso siempre es positivo.<\/p>\n<p style=\"text-align: justify;\">Ahora bien, ya que utilizamos las r\u00fabricas, utilicemos las mismas realizando evaluaci\u00f3n formativa, que hay mil estudios que demuestran que es una de las medidas que m\u00e1s mejora el aprendizaje de los alumnos. \u00bfY qu\u00e9 quiere decir exactamente hacer evaluaci\u00f3n formativa con r\u00fabricas?<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\"><strong>Primero:<\/strong> solo si los alumnos ya han utilizado r\u00fabricas con anterioridad, ser\u00e1 necesario que la r\u00fabrica la creen ellos mismos. La reflexi\u00f3n que conlleva pensar en cu\u00e1les son los aspectos que hay que valorar de una tarea o de una habilidad y definir, como m\u00ednimo, el nivel experto s\u00ed que da elementos claros de aprendizaje. Antes de empezar a realizar la tarea (o poco despu\u00e9s de iniciarse) provocamos la reflexi\u00f3n en los alumnos de lo que est\u00e1n llevando a cabo. Y esta reflexi\u00f3n, los lleva a valorar si lo que est\u00e1n haciendo se corresponde con\u00a0 lo esperado o si es necesario introducir mejoras.<\/p>\n<p style=\"text-align: justify;\"><strong>Segundo:<\/strong> si la han creado ellos es evidente pero, si la r\u00fabrica la creamos nosotros, es imprescindible que la tengan con anterioridad y se la puedan hacer suya. Es necesario que est\u00e9 redactada de forma que la puedan entender y que les ayude a detectar los errores m\u00e1s comunes.<\/p>\n<p style=\"text-align: justify;\"><strong>Tercero:<\/strong> habr\u00e1 que utilizar la r\u00fabrica varias veces <strong>sin<\/strong> utilizar puntuaci\u00f3n num\u00e9rica. Si est\u00e1n presentando alg\u00fan objeto, se puede utilizar la r\u00fabrica para hacer una primera evaluaci\u00f3n cualitativa que permita introducir mejoras. Igualmente si est\u00e1n trabajando alguna habilidad (hablar en p\u00fablico, resumir un texto &#8230;). La r\u00fabrica sin calificaci\u00f3n les permitir\u00e1 ver lo que pueden mejorar. Y, si lo hacen, su aprendizaje mejorar\u00e1. M\u00e1s adelante, ya se utilizar\u00e1 con calificaci\u00f3n cuantitativa si es necesario.<\/p>\n<p style=\"text-align: justify;\"><strong>Cuarto:<\/strong> llegados ya el d\u00eda de la entrega final (alg\u00fan d\u00eda se debe realizar la entrega o la evaluaci\u00f3n de una habilidad para certificar), implicarlos. Si los alumnos se eval\u00faan entre ellos (coevaluaci\u00f3n) y se eval\u00faan a s\u00ed mismos (autoevaluaci\u00f3n), la r\u00fabrica continuar\u00e1 teniendo funciones formativas. Mientras los alumnos eval\u00faan las tareas o habilidades de los dem\u00e1s compa\u00f1eros, est\u00e1n reflexionando sobre c\u00f3mo deber\u00eda ser la tarea o la habilidad. Por tanto, siguen haciendo camino de aprendizaje.<\/p>\n<p style=\"text-align: justify;\">Si, adem\u00e1s, la utilizamos los profesores y nos sirve para obtener una nota final cuando se cierra la evaluaci\u00f3n (evaluaci\u00f3n sumativa), pues perfecto. El alumno tendr\u00e1 m\u00e1s sensaci\u00f3n de justicia y entender\u00e1 mejor la calificaci\u00f3n. Cuantos profesores que van a oposiciones no querr\u00edan poder ver la r\u00fabrica con que los han evaluado, aunque no puedan cambiar nada.<\/p>\n<p style=\"text-align: justify;\">Pero hay que tener bien claro que este \u00faltimo paso, el de utilizar una r\u00fabrica para hacer una evaluaci\u00f3n final, nada tiene que ver con evaluaci\u00f3n formativa. Desenga\u00f1\u00e9monos, cuando un alumno ha entregado una tarea que ya no puede mejorar y le damos un nota, por mucha r\u00fabrica que la acompa\u00f1e, no habr\u00e1 reflexi\u00f3n sobre los errores cometidos ni mejora del aprendizaje.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mucha gente todav\u00eda cree que evaluar con r\u00fabricas es realizar evaluaci\u00f3n formativa y, en muchos casos, no es as\u00ed. Una r\u00fabrica, de hecho, proporciona criterios claros a la hora de evaluar una tarea. Ahora bien, esto se puede hacer para&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3407,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51,98,59],"tags":[],"class_list":["post-3410","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-abp-es","category-avaluacio-es","category-rubricas","post-archive"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00fabricas y evaluaci\u00f3n formativa - Tecnocentres<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tecnocentres.org\/es\/blog\/2018\/10\/11\/rubricas-y-evaluacion-formativa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00fabricas y evaluaci\u00f3n formativa - Tecnocentres\" \/>\n<meta property=\"og:description\" content=\"Mucha gente todav\u00eda cree que evaluar con r\u00fabricas es realizar evaluaci\u00f3n formativa y, en muchos casos, no es as\u00ed. Una r\u00fabrica, de hecho, proporciona criterios claros a la hora de evaluar una tarea. Ahora bien, esto se puede hacer para...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tecnocentres.org\/es\/blog\/2018\/10\/11\/rubricas-y-evaluacion-formativa\/\" \/>\n<meta property=\"og:site_name\" content=\"Tecnocentres\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-11T16:30:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tecnocentres.org\/wp-content\/uploads\/2018\/10\/corubrics12.png\" \/>\n\t<meta property=\"og:image:width\" content=\"695\" \/>\n\t<meta property=\"og:image:height\" content=\"357\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jaume Feliu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jfeliua\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jaume Feliu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2018\\\/10\\\/11\\\/rubricas-y-evaluacion-formativa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2018\\\/10\\\/11\\\/rubricas-y-evaluacion-formativa\\\/\"},\"author\":{\"name\":\"Jaume Feliu\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#\\\/schema\\\/person\\\/b2eb569e95072dedf967f0036be08adf\"},\"headline\":\"R\u00fabricas y evaluaci\u00f3n formativa\",\"datePublished\":\"2018-10-11T16:30:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2018\\\/10\\\/11\\\/rubricas-y-evaluacion-formativa\\\/\"},\"wordCount\":652,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2018\\\/10\\\/11\\\/rubricas-y-evaluacion-formativa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tecnocentres.org\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/corubrics12.png\",\"articleSection\":[\"ABP\",\"Avaluaci\u00f3\",\"R\u00fabricas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2018\\\/10\\\/11\\\/rubricas-y-evaluacion-formativa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2018\\\/10\\\/11\\\/rubricas-y-evaluacion-formativa\\\/\",\"url\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2018\\\/10\\\/11\\\/rubricas-y-evaluacion-formativa\\\/\",\"name\":\"R\u00fabricas y evaluaci\u00f3n formativa - Tecnocentres\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2018\\\/10\\\/11\\\/rubricas-y-evaluacion-formativa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2018\\\/10\\\/11\\\/rubricas-y-evaluacion-formativa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tecnocentres.org\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/corubrics12.png\",\"datePublished\":\"2018-10-11T16:30:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#\\\/schema\\\/person\\\/b2eb569e95072dedf967f0036be08adf\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2018\\\/10\\\/11\\\/rubricas-y-evaluacion-formativa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2018\\\/10\\\/11\\\/rubricas-y-evaluacion-formativa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2018\\\/10\\\/11\\\/rubricas-y-evaluacion-formativa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tecnocentres.org\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/corubrics12.png\",\"contentUrl\":\"https:\\\/\\\/tecnocentres.org\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/corubrics12.png\",\"width\":695,\"height\":357},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2018\\\/10\\\/11\\\/rubricas-y-evaluacion-formativa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00fabricas y evaluaci\u00f3n formativa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/\",\"name\":\"Tecnocentres\",\"description\":\"Blog de Jaume Feliu\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#\\\/schema\\\/person\\\/b2eb569e95072dedf967f0036be08adf\",\"name\":\"Jaume Feliu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g\",\"caption\":\"Jaume Feliu\"},\"sameAs\":[\"https:\\\/\\\/tecnocentres.org\",\"https:\\\/\\\/x.com\\\/jfeliua\"],\"url\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00fabricas y evaluaci\u00f3n formativa - Tecnocentres","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tecnocentres.org\/es\/blog\/2018\/10\/11\/rubricas-y-evaluacion-formativa\/","og_locale":"es_ES","og_type":"article","og_title":"R\u00fabricas y evaluaci\u00f3n formativa - Tecnocentres","og_description":"Mucha gente todav\u00eda cree que evaluar con r\u00fabricas es realizar evaluaci\u00f3n formativa y, en muchos casos, no es as\u00ed. Una r\u00fabrica, de hecho, proporciona criterios claros a la hora de evaluar una tarea. Ahora bien, esto se puede hacer para...","og_url":"https:\/\/tecnocentres.org\/es\/blog\/2018\/10\/11\/rubricas-y-evaluacion-formativa\/","og_site_name":"Tecnocentres","article_published_time":"2018-10-11T16:30:41+00:00","og_image":[{"width":695,"height":357,"url":"https:\/\/tecnocentres.org\/wp-content\/uploads\/2018\/10\/corubrics12.png","type":"image\/png"}],"author":"Jaume Feliu","twitter_card":"summary_large_image","twitter_creator":"@jfeliua","twitter_misc":{"Escrito por":"Jaume Feliu","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tecnocentres.org\/es\/blog\/2018\/10\/11\/rubricas-y-evaluacion-formativa\/#article","isPartOf":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2018\/10\/11\/rubricas-y-evaluacion-formativa\/"},"author":{"name":"Jaume Feliu","@id":"https:\/\/tecnocentres.org\/es\/#\/schema\/person\/b2eb569e95072dedf967f0036be08adf"},"headline":"R\u00fabricas y evaluaci\u00f3n formativa","datePublished":"2018-10-11T16:30:41+00:00","mainEntityOfPage":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2018\/10\/11\/rubricas-y-evaluacion-formativa\/"},"wordCount":652,"commentCount":1,"image":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2018\/10\/11\/rubricas-y-evaluacion-formativa\/#primaryimage"},"thumbnailUrl":"https:\/\/tecnocentres.org\/wp-content\/uploads\/2018\/10\/corubrics12.png","articleSection":["ABP","Avaluaci\u00f3","R\u00fabricas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tecnocentres.org\/es\/blog\/2018\/10\/11\/rubricas-y-evaluacion-formativa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tecnocentres.org\/es\/blog\/2018\/10\/11\/rubricas-y-evaluacion-formativa\/","url":"https:\/\/tecnocentres.org\/es\/blog\/2018\/10\/11\/rubricas-y-evaluacion-formativa\/","name":"R\u00fabricas y evaluaci\u00f3n formativa - Tecnocentres","isPartOf":{"@id":"https:\/\/tecnocentres.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2018\/10\/11\/rubricas-y-evaluacion-formativa\/#primaryimage"},"image":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2018\/10\/11\/rubricas-y-evaluacion-formativa\/#primaryimage"},"thumbnailUrl":"https:\/\/tecnocentres.org\/wp-content\/uploads\/2018\/10\/corubrics12.png","datePublished":"2018-10-11T16:30:41+00:00","author":{"@id":"https:\/\/tecnocentres.org\/es\/#\/schema\/person\/b2eb569e95072dedf967f0036be08adf"},"breadcrumb":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2018\/10\/11\/rubricas-y-evaluacion-formativa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tecnocentres.org\/es\/blog\/2018\/10\/11\/rubricas-y-evaluacion-formativa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tecnocentres.org\/es\/blog\/2018\/10\/11\/rubricas-y-evaluacion-formativa\/#primaryimage","url":"https:\/\/tecnocentres.org\/wp-content\/uploads\/2018\/10\/corubrics12.png","contentUrl":"https:\/\/tecnocentres.org\/wp-content\/uploads\/2018\/10\/corubrics12.png","width":695,"height":357},{"@type":"BreadcrumbList","@id":"https:\/\/tecnocentres.org\/es\/blog\/2018\/10\/11\/rubricas-y-evaluacion-formativa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/tecnocentres.org\/es\/"},{"@type":"ListItem","position":2,"name":"R\u00fabricas y evaluaci\u00f3n formativa"}]},{"@type":"WebSite","@id":"https:\/\/tecnocentres.org\/es\/#website","url":"https:\/\/tecnocentres.org\/es\/","name":"Tecnocentres","description":"Blog de Jaume Feliu","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tecnocentres.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/tecnocentres.org\/es\/#\/schema\/person\/b2eb569e95072dedf967f0036be08adf","name":"Jaume Feliu","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g","caption":"Jaume Feliu"},"sameAs":["https:\/\/tecnocentres.org","https:\/\/x.com\/jfeliua"],"url":"https:\/\/tecnocentres.org\/es\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/posts\/3410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/comments?post=3410"}],"version-history":[{"count":0,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/posts\/3410\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/media\/3407"}],"wp:attachment":[{"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/media?parent=3410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/categories?post=3410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/tags?post=3410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}