{"id":1658,"date":"2017-07-11T19:56:59","date_gmt":"2017-07-11T17:56:59","guid":{"rendered":"http:\/\/tecnocentres.org\/nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0\/"},"modified":"2017-07-11T19:56:59","modified_gmt":"2017-07-11T17:56:59","slug":"nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0","status":"publish","type":"post","link":"https:\/\/tecnocentres.org\/es\/blog\/2017\/07\/11\/nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0\/","title":{"rendered":"Nueva versi\u00f3n del cuaderno virtual (4.0) y del Assistatut (2.0)"},"content":{"rendered":"<p style=\"text-align: justify;\">Acabo de publicar una nueva versi\u00f3n del cuaderno virtual, la 4.0, y del Assistatut, la 2.0. Las dos mejoras m\u00e1s importantes son que se eliminan las diferentes plantillas y las unifican todas en una. Adem\u00e1s, ahora se permite que las sesiones duren 2 horas.<!--more--><\/p>\n<p style=\"text-align: justify;\">Como es l\u00f3gico, se han implementado m\u00e1s mejoras menos destacadas: ocultaci\u00f3n autom\u00e1tica columnas una vez han pasado los datos, permitir definir observaciones est\u00e1ndares y algunas m\u00e1s.<\/p>\n<p style=\"text-align: justify;\">Se puede encontrar toda la informaci\u00f3n en las webs correspondientes:<\/p>\n<ul>\n<li style=\"text-align: left;\"><a href=\"http:\/\/cv.tecnocentres.org\" target=\"_blank\" rel=\"noopener noreferrer\">Cuaderno virtual del profesor<\/a><\/li>\n<li style=\"text-align: left;\"><a href=\"http:\/\/assistatut-es.tecnocentres.org\" target=\"_blank\" rel=\"noopener noreferrer\">Assistatut<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Acabo de publicar una nueva versi\u00f3n del cuaderno virtual, la 4.0, y del Assistatut, la 2.0. Las dos mejoras m\u00e1s importantes son que se eliminan las diferentes plantillas y las unifican todas en una. Adem\u00e1s, ahora se permite que las&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49,46],"tags":[],"class_list":["post-1658","post","type-post","status-publish","format-standard","hentry","category-herramientas-2-0","category-profesores","post-archive"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nueva versi\u00f3n del cuaderno virtual (4.0) y del Assistatut (2.0) - Tecnocentres<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tecnocentres.org\/es\/blog\/2017\/07\/11\/nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nueva versi\u00f3n del cuaderno virtual (4.0) y del Assistatut (2.0) - Tecnocentres\" \/>\n<meta property=\"og:description\" content=\"Acabo de publicar una nueva versi\u00f3n del cuaderno virtual, la 4.0, y del Assistatut, la 2.0. Las dos mejoras m\u00e1s importantes son que se eliminan las diferentes plantillas y las unifican todas en una. Adem\u00e1s, ahora se permite que las...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tecnocentres.org\/es\/blog\/2017\/07\/11\/nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0\/\" \/>\n<meta property=\"og:site_name\" content=\"Tecnocentres\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-11T17:56:59+00:00\" \/>\n<meta name=\"author\" content=\"Jaume Feliu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jfeliua\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jaume Feliu\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2017\\\/07\\\/11\\\/nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2017\\\/07\\\/11\\\/nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0\\\/\"},\"author\":{\"name\":\"Jaume Feliu\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#\\\/schema\\\/person\\\/b2eb569e95072dedf967f0036be08adf\"},\"headline\":\"Nueva versi\u00f3n del cuaderno virtual (4.0) y del Assistatut (2.0)\",\"datePublished\":\"2017-07-11T17:56:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2017\\\/07\\\/11\\\/nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0\\\/\"},\"wordCount\":101,\"commentCount\":3,\"articleSection\":[\"Herramientas 2.0\",\"Profesores\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2017\\\/07\\\/11\\\/nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2017\\\/07\\\/11\\\/nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0\\\/\",\"url\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2017\\\/07\\\/11\\\/nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0\\\/\",\"name\":\"Nueva versi\u00f3n del cuaderno virtual (4.0) y del Assistatut (2.0) - Tecnocentres\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#website\"},\"datePublished\":\"2017-07-11T17:56:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#\\\/schema\\\/person\\\/b2eb569e95072dedf967f0036be08adf\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2017\\\/07\\\/11\\\/nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2017\\\/07\\\/11\\\/nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2017\\\/07\\\/11\\\/nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nueva versi\u00f3n del cuaderno virtual (4.0) y del Assistatut (2.0)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/\",\"name\":\"Tecnocentres\",\"description\":\"Blog de Jaume Feliu\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#\\\/schema\\\/person\\\/b2eb569e95072dedf967f0036be08adf\",\"name\":\"Jaume Feliu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g\",\"caption\":\"Jaume Feliu\"},\"sameAs\":[\"https:\\\/\\\/tecnocentres.org\",\"https:\\\/\\\/x.com\\\/jfeliua\"],\"url\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nueva versi\u00f3n del cuaderno virtual (4.0) y del Assistatut (2.0) - Tecnocentres","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tecnocentres.org\/es\/blog\/2017\/07\/11\/nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0\/","og_locale":"es_ES","og_type":"article","og_title":"Nueva versi\u00f3n del cuaderno virtual (4.0) y del Assistatut (2.0) - Tecnocentres","og_description":"Acabo de publicar una nueva versi\u00f3n del cuaderno virtual, la 4.0, y del Assistatut, la 2.0. Las dos mejoras m\u00e1s importantes son que se eliminan las diferentes plantillas y las unifican todas en una. Adem\u00e1s, ahora se permite que las...","og_url":"https:\/\/tecnocentres.org\/es\/blog\/2017\/07\/11\/nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0\/","og_site_name":"Tecnocentres","article_published_time":"2017-07-11T17:56:59+00:00","author":"Jaume Feliu","twitter_card":"summary_large_image","twitter_creator":"@jfeliua","twitter_misc":{"Escrito por":"Jaume Feliu"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tecnocentres.org\/es\/blog\/2017\/07\/11\/nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0\/#article","isPartOf":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2017\/07\/11\/nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0\/"},"author":{"name":"Jaume Feliu","@id":"https:\/\/tecnocentres.org\/es\/#\/schema\/person\/b2eb569e95072dedf967f0036be08adf"},"headline":"Nueva versi\u00f3n del cuaderno virtual (4.0) y del Assistatut (2.0)","datePublished":"2017-07-11T17:56:59+00:00","mainEntityOfPage":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2017\/07\/11\/nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0\/"},"wordCount":101,"commentCount":3,"articleSection":["Herramientas 2.0","Profesores"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tecnocentres.org\/es\/blog\/2017\/07\/11\/nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tecnocentres.org\/es\/blog\/2017\/07\/11\/nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0\/","url":"https:\/\/tecnocentres.org\/es\/blog\/2017\/07\/11\/nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0\/","name":"Nueva versi\u00f3n del cuaderno virtual (4.0) y del Assistatut (2.0) - Tecnocentres","isPartOf":{"@id":"https:\/\/tecnocentres.org\/es\/#website"},"datePublished":"2017-07-11T17:56:59+00:00","author":{"@id":"https:\/\/tecnocentres.org\/es\/#\/schema\/person\/b2eb569e95072dedf967f0036be08adf"},"breadcrumb":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2017\/07\/11\/nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tecnocentres.org\/es\/blog\/2017\/07\/11\/nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tecnocentres.org\/es\/blog\/2017\/07\/11\/nueva-version-del-cuaderno-virtual-4-0-y-del-assistatut-2-0\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/tecnocentres.org\/es\/"},{"@type":"ListItem","position":2,"name":"Nueva versi\u00f3n del cuaderno virtual (4.0) y del Assistatut (2.0)"}]},{"@type":"WebSite","@id":"https:\/\/tecnocentres.org\/es\/#website","url":"https:\/\/tecnocentres.org\/es\/","name":"Tecnocentres","description":"Blog de Jaume Feliu","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tecnocentres.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/tecnocentres.org\/es\/#\/schema\/person\/b2eb569e95072dedf967f0036be08adf","name":"Jaume Feliu","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g","caption":"Jaume Feliu"},"sameAs":["https:\/\/tecnocentres.org","https:\/\/x.com\/jfeliua"],"url":"https:\/\/tecnocentres.org\/es\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/posts\/1658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/comments?post=1658"}],"version-history":[{"count":0,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/posts\/1658\/revisions"}],"wp:attachment":[{"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/media?parent=1658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/categories?post=1658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/tags?post=1658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}