{"id":1586,"date":"2015-04-03T18:46:31","date_gmt":"2015-04-03T18:46:31","guid":{"rendered":"http:\/\/tecnocentres.org\/cuaderno-virtual-del-profesor-version-3-1\/"},"modified":"2015-04-03T18:46:31","modified_gmt":"2015-04-03T18:46:31","slug":"cuaderno-virtual-del-profesor-version-3-1","status":"publish","type":"post","link":"https:\/\/tecnocentres.org\/es\/blog\/2015\/04\/03\/cuaderno-virtual-del-profesor-version-3-1\/","title":{"rendered":"Cuaderno virtual del profesor, versi\u00f3n 3.1"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/tecnocentres.org\/wp-content\/uploads\/2015\/04\/qv31.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-885\" src=\"http:\/\/tecnocentres.org\/wp-content\/uploads\/2015\/04\/qv31-300x199.png\" alt=\"qv31\" width=\"223\" height=\"148\" srcset=\"https:\/\/tecnocentres.org\/wp-content\/uploads\/2015\/04\/qv31-300x199.png 300w, https:\/\/tecnocentres.org\/wp-content\/uploads\/2015\/04\/qv31.png 486w\" sizes=\"auto, (max-width: 223px) 100vw, 223px\" \/><\/a>Estamos ya en el tercer trimestre y muchos equipos directivos comienzan a planificar el curso que viene. Para la mayor\u00eda de profesores a\u00fan es pronto, que bastante tenemos con el tercer trimestre. No obstante, y para quien quiera ir preparando el pr\u00f3ximo curso y probando opciones, he publicado la versi\u00f3n 3.1 del Cuaderno virtual del profesor, con algunas novedades.<\/p>\n<p style=\"text-align: justify;\"><!--more-->Aparte de corregir algunos errores detectados, esta nueva versi\u00f3n, incorpora las siguientes novedades:<\/p>\n<ul>\n<li style=\"text-align: justify;\">Se ha a\u00f1adido una opci\u00f3n en el men\u00fa para ir a la fecha actual. S\u00f3lo funciona si se est\u00e1 en la hoja <em>Sesiones, Asistencia o Actitud.<\/em> As\u00ed no hay que ir buscando la fecha con la barra de desplazamiento horizontal o vertical.<\/li>\n<li style=\"text-align: justify;\">Se ha a\u00f1adido una hoja, de nombre<em> Ficha del alumno<\/em>, que permite seleccionar el alumno que se desea consultar y ver todos los datos del cuaderno (asistencia, notas de todas las evaluaciones, foto, incidencias de disciplina .. .).<\/li>\n<li style=\"text-align: justify;\">Se ha configurado la hoja <em>Disciplin<\/em>a para poder elegir al alumno de un desplegable donde salen los nombres. As\u00ed no hay que consultar el n\u00famero de alumno.<\/li>\n<li style=\"text-align: justify;\">Se a\u00f1ade una columna en la hoja <em>Prog<\/em> para poner observaciones.<\/li>\n<li style=\"text-align: justify;\">Se cambia el formato de la fecha de la hoja <em>Sesiones<\/em> para que aparezca el d\u00eda de la semana en la fecha.<\/li>\n<li style=\"text-align: justify;\">Se crea una opci\u00f3n en el men\u00fa que permite recuperar autom\u00e1ticamente las fotograf\u00edas de los alumnos y los mails de las familias, siempre y cuando se indique en la hoja <em>Datos del curso<\/em> cu\u00e1l es esta hoja.<\/li>\n<\/ul>\n<p>Si quieren utilizar esta nueva versi\u00f3n, se puede encontrar en:\u00a0<a href=\"http:\/\/cv.tecnocentres.org\" target=\"_blank\" rel=\"noopener noreferrer\">hhttp:\/\/cv.tecnocentres.org<\/a><\/p>\n<p style=\"text-align: justify;\">Si ya est\u00e1 utilizando una versi\u00f3n antigua del cuaderno, espere a terminar el curso y en el pr\u00f3ximo utilice el nuevo. El traspaso es complicado y no es necesario la pena.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estamos ya en el tercer trimestre y muchos equipos directivos comienzan a planificar el curso que viene. Para la mayor\u00eda de profesores a\u00fan es pronto, que bastante tenemos con el tercer trimestre. No obstante, y para quien quiera ir preparando&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37,38,40,46],"tags":[],"class_list":["post-1586","post","type-post","status-publish","format-standard","hentry","category-alumnos","category-centros","category-direccion","category-profesores","post-archive"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cuaderno virtual del profesor, versi\u00f3n 3.1 - Tecnocentres<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tecnocentres.org\/es\/blog\/2015\/04\/03\/cuaderno-virtual-del-profesor-version-3-1\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuaderno virtual del profesor, versi\u00f3n 3.1 - Tecnocentres\" \/>\n<meta property=\"og:description\" content=\"Estamos ya en el tercer trimestre y muchos equipos directivos comienzan a planificar el curso que viene. Para la mayor\u00eda de profesores a\u00fan es pronto, que bastante tenemos con el tercer trimestre. No obstante, y para quien quiera ir preparando...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tecnocentres.org\/es\/blog\/2015\/04\/03\/cuaderno-virtual-del-profesor-version-3-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Tecnocentres\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-03T18:46:31+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/tecnocentres.org\/wp-content\/uploads\/2015\/04\/qv31-300x199.png\" \/>\n<meta name=\"author\" content=\"Jaume Feliu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jfeliua\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jaume Feliu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2015\\\/04\\\/03\\\/cuaderno-virtual-del-profesor-version-3-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2015\\\/04\\\/03\\\/cuaderno-virtual-del-profesor-version-3-1\\\/\"},\"author\":{\"name\":\"Jaume Feliu\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#\\\/schema\\\/person\\\/b2eb569e95072dedf967f0036be08adf\"},\"headline\":\"Cuaderno virtual del profesor, versi\u00f3n 3.1\",\"datePublished\":\"2015-04-03T18:46:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2015\\\/04\\\/03\\\/cuaderno-virtual-del-profesor-version-3-1\\\/\"},\"wordCount\":316,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2015\\\/04\\\/03\\\/cuaderno-virtual-del-profesor-version-3-1\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/tecnocentres.org\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/qv31-300x199.png\",\"articleSection\":[\"Alumnos\",\"Centros\",\"Direcci\u00f3n\",\"Profesores\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2015\\\/04\\\/03\\\/cuaderno-virtual-del-profesor-version-3-1\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2015\\\/04\\\/03\\\/cuaderno-virtual-del-profesor-version-3-1\\\/\",\"url\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2015\\\/04\\\/03\\\/cuaderno-virtual-del-profesor-version-3-1\\\/\",\"name\":\"Cuaderno virtual del profesor, versi\u00f3n 3.1 - Tecnocentres\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2015\\\/04\\\/03\\\/cuaderno-virtual-del-profesor-version-3-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2015\\\/04\\\/03\\\/cuaderno-virtual-del-profesor-version-3-1\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/tecnocentres.org\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/qv31-300x199.png\",\"datePublished\":\"2015-04-03T18:46:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#\\\/schema\\\/person\\\/b2eb569e95072dedf967f0036be08adf\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2015\\\/04\\\/03\\\/cuaderno-virtual-del-profesor-version-3-1\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2015\\\/04\\\/03\\\/cuaderno-virtual-del-profesor-version-3-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2015\\\/04\\\/03\\\/cuaderno-virtual-del-profesor-version-3-1\\\/#primaryimage\",\"url\":\"http:\\\/\\\/tecnocentres.org\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/qv31-300x199.png\",\"contentUrl\":\"http:\\\/\\\/tecnocentres.org\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/qv31-300x199.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/2015\\\/04\\\/03\\\/cuaderno-virtual-del-profesor-version-3-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuaderno virtual del profesor, versi\u00f3n 3.1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/\",\"name\":\"Tecnocentres\",\"description\":\"Blog de Jaume Feliu\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/#\\\/schema\\\/person\\\/b2eb569e95072dedf967f0036be08adf\",\"name\":\"Jaume Feliu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g\",\"caption\":\"Jaume Feliu\"},\"sameAs\":[\"https:\\\/\\\/tecnocentres.org\",\"https:\\\/\\\/x.com\\\/jfeliua\"],\"url\":\"https:\\\/\\\/tecnocentres.org\\\/es\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuaderno virtual del profesor, versi\u00f3n 3.1 - Tecnocentres","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tecnocentres.org\/es\/blog\/2015\/04\/03\/cuaderno-virtual-del-profesor-version-3-1\/","og_locale":"es_ES","og_type":"article","og_title":"Cuaderno virtual del profesor, versi\u00f3n 3.1 - Tecnocentres","og_description":"Estamos ya en el tercer trimestre y muchos equipos directivos comienzan a planificar el curso que viene. Para la mayor\u00eda de profesores a\u00fan es pronto, que bastante tenemos con el tercer trimestre. No obstante, y para quien quiera ir preparando...","og_url":"https:\/\/tecnocentres.org\/es\/blog\/2015\/04\/03\/cuaderno-virtual-del-profesor-version-3-1\/","og_site_name":"Tecnocentres","article_published_time":"2015-04-03T18:46:31+00:00","og_image":[{"url":"http:\/\/tecnocentres.org\/wp-content\/uploads\/2015\/04\/qv31-300x199.png","type":"","width":"","height":""}],"author":"Jaume Feliu","twitter_card":"summary_large_image","twitter_creator":"@jfeliua","twitter_misc":{"Escrito por":"Jaume Feliu","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tecnocentres.org\/es\/blog\/2015\/04\/03\/cuaderno-virtual-del-profesor-version-3-1\/#article","isPartOf":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2015\/04\/03\/cuaderno-virtual-del-profesor-version-3-1\/"},"author":{"name":"Jaume Feliu","@id":"https:\/\/tecnocentres.org\/es\/#\/schema\/person\/b2eb569e95072dedf967f0036be08adf"},"headline":"Cuaderno virtual del profesor, versi\u00f3n 3.1","datePublished":"2015-04-03T18:46:31+00:00","mainEntityOfPage":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2015\/04\/03\/cuaderno-virtual-del-profesor-version-3-1\/"},"wordCount":316,"commentCount":0,"image":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2015\/04\/03\/cuaderno-virtual-del-profesor-version-3-1\/#primaryimage"},"thumbnailUrl":"http:\/\/tecnocentres.org\/wp-content\/uploads\/2015\/04\/qv31-300x199.png","articleSection":["Alumnos","Centros","Direcci\u00f3n","Profesores"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tecnocentres.org\/es\/blog\/2015\/04\/03\/cuaderno-virtual-del-profesor-version-3-1\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tecnocentres.org\/es\/blog\/2015\/04\/03\/cuaderno-virtual-del-profesor-version-3-1\/","url":"https:\/\/tecnocentres.org\/es\/blog\/2015\/04\/03\/cuaderno-virtual-del-profesor-version-3-1\/","name":"Cuaderno virtual del profesor, versi\u00f3n 3.1 - Tecnocentres","isPartOf":{"@id":"https:\/\/tecnocentres.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2015\/04\/03\/cuaderno-virtual-del-profesor-version-3-1\/#primaryimage"},"image":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2015\/04\/03\/cuaderno-virtual-del-profesor-version-3-1\/#primaryimage"},"thumbnailUrl":"http:\/\/tecnocentres.org\/wp-content\/uploads\/2015\/04\/qv31-300x199.png","datePublished":"2015-04-03T18:46:31+00:00","author":{"@id":"https:\/\/tecnocentres.org\/es\/#\/schema\/person\/b2eb569e95072dedf967f0036be08adf"},"breadcrumb":{"@id":"https:\/\/tecnocentres.org\/es\/blog\/2015\/04\/03\/cuaderno-virtual-del-profesor-version-3-1\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tecnocentres.org\/es\/blog\/2015\/04\/03\/cuaderno-virtual-del-profesor-version-3-1\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tecnocentres.org\/es\/blog\/2015\/04\/03\/cuaderno-virtual-del-profesor-version-3-1\/#primaryimage","url":"http:\/\/tecnocentres.org\/wp-content\/uploads\/2015\/04\/qv31-300x199.png","contentUrl":"http:\/\/tecnocentres.org\/wp-content\/uploads\/2015\/04\/qv31-300x199.png"},{"@type":"BreadcrumbList","@id":"https:\/\/tecnocentres.org\/es\/blog\/2015\/04\/03\/cuaderno-virtual-del-profesor-version-3-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/tecnocentres.org\/es\/"},{"@type":"ListItem","position":2,"name":"Cuaderno virtual del profesor, versi\u00f3n 3.1"}]},{"@type":"WebSite","@id":"https:\/\/tecnocentres.org\/es\/#website","url":"https:\/\/tecnocentres.org\/es\/","name":"Tecnocentres","description":"Blog de Jaume Feliu","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tecnocentres.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/tecnocentres.org\/es\/#\/schema\/person\/b2eb569e95072dedf967f0036be08adf","name":"Jaume Feliu","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04319ca8610bfe2a04fca8f0d7d42c7e87e4bbe1c687e39a0192f567098d464e?s=96&d=mm&r=g","caption":"Jaume Feliu"},"sameAs":["https:\/\/tecnocentres.org","https:\/\/x.com\/jfeliua"],"url":"https:\/\/tecnocentres.org\/es\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/posts\/1586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/comments?post=1586"}],"version-history":[{"count":0,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/posts\/1586\/revisions"}],"wp:attachment":[{"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/media?parent=1586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/categories?post=1586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tecnocentres.org\/es\/wp-json\/wp\/v2\/tags?post=1586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}